{"id":6945,"date":"2025-10-16T14:49:41","date_gmt":"2025-10-16T12:49:41","guid":{"rendered":"https:\/\/nickswellenfieber.ch\/winterrabatt\/"},"modified":"2025-10-16T14:53:31","modified_gmt":"2025-10-16T12:53:31","slug":"winterrabatt","status":"publish","type":"post","link":"https:\/\/nickswellenfieber.ch\/fr\/winterrabatt\/","title":{"rendered":"Winterrabatt"},"content":{"rendered":"<section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"2552\" height=\"1437\" src=\"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg 2552w, https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1-300x169.jpg 300w, https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1-1024x577.jpg 1024w\" sizes=\"auto, (max-width: 2552px) 100vw, 2552px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":6940,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Winterrabatt - Nicks Wellenfieber<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Winterrabatt - Nicks Wellenfieber\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/\" \/>\n<meta property=\"og:site_name\" content=\"Nicks Wellenfieber\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-16T12:49:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-16T12:53:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2552\" \/>\n\t<meta property=\"og:image:height\" content=\"1437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"t8.wellenfieber\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"t8.wellenfieber\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/\",\"url\":\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/\",\"name\":\"Winterrabatt - Nicks Wellenfieber\",\"isPartOf\":{\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg\",\"datePublished\":\"2025-10-16T12:49:41+00:00\",\"dateModified\":\"2025-10-16T12:53:31+00:00\",\"author\":{\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/#\/schema\/person\/297c81fc2a096881bcbf7e823e7f91bc\"},\"breadcrumb\":{\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#primaryimage\",\"url\":\"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg\",\"contentUrl\":\"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg\",\"width\":2552,\"height\":1437},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nickswellenfieber.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winterrabatt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/#website\",\"url\":\"https:\/\/nickswellenfieber.ch\/de\/\",\"name\":\"Nicks Wellenfieber\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nickswellenfieber.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/#\/schema\/person\/297c81fc2a096881bcbf7e823e7f91bc\",\"name\":\"t8.wellenfieber\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/nickswellenfieber.ch\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/73c4c012e6b09be4a1b56b81cd9c423278fd8271a1333193c5816f43512dcab8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/73c4c012e6b09be4a1b56b81cd9c423278fd8271a1333193c5816f43512dcab8?s=96&d=mm&r=g\",\"caption\":\"t8.wellenfieber\"},\"url\":\"https:\/\/nickswellenfieber.ch\/fr\/author\/t8-wellenfieber\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Winterrabatt - Nicks Wellenfieber","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/","og_locale":"fr_FR","og_type":"article","og_title":"Winterrabatt - Nicks Wellenfieber","og_url":"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/","og_site_name":"Nicks Wellenfieber","article_published_time":"2025-10-16T12:49:41+00:00","article_modified_time":"2025-10-16T12:53:31+00:00","og_image":[{"width":2552,"height":1437,"url":"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg","type":"image\/jpeg"}],"author":"t8.wellenfieber","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"t8.wellenfieber"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/","url":"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/","name":"Winterrabatt - Nicks Wellenfieber","isPartOf":{"@id":"https:\/\/nickswellenfieber.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#primaryimage"},"image":{"@id":"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#primaryimage"},"thumbnailUrl":"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg","datePublished":"2025-10-16T12:49:41+00:00","dateModified":"2025-10-16T12:53:31+00:00","author":{"@id":"https:\/\/nickswellenfieber.ch\/de\/#\/schema\/person\/297c81fc2a096881bcbf7e823e7f91bc"},"breadcrumb":{"@id":"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#primaryimage","url":"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg","contentUrl":"https:\/\/nickswellenfieber.ch\/wp-content\/uploads\/2025\/10\/nicks-1.jpg","width":2552,"height":1437},{"@type":"BreadcrumbList","@id":"https:\/\/nickswellenfieber.ch\/de\/winterrabatt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nickswellenfieber.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Winterrabatt"}]},{"@type":"WebSite","@id":"https:\/\/nickswellenfieber.ch\/de\/#website","url":"https:\/\/nickswellenfieber.ch\/de\/","name":"Nicks Wellenfieber","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nickswellenfieber.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/nickswellenfieber.ch\/de\/#\/schema\/person\/297c81fc2a096881bcbf7e823e7f91bc","name":"t8.wellenfieber","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nickswellenfieber.ch\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/73c4c012e6b09be4a1b56b81cd9c423278fd8271a1333193c5816f43512dcab8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73c4c012e6b09be4a1b56b81cd9c423278fd8271a1333193c5816f43512dcab8?s=96&d=mm&r=g","caption":"t8.wellenfieber"},"url":"https:\/\/nickswellenfieber.ch\/fr\/author\/t8-wellenfieber\/"}]}},"_links":{"self":[{"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/posts\/6945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/comments?post=6945"}],"version-history":[{"count":1,"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/posts\/6945\/revisions"}],"predecessor-version":[{"id":6947,"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/posts\/6945\/revisions\/6947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/media\/6940"}],"wp:attachment":[{"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/media?parent=6945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/categories?post=6945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nickswellenfieber.ch\/fr\/wp-json\/wp\/v2\/tags?post=6945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}